{"id":130,"date":"2015-04-19T09:14:11","date_gmt":"2015-04-19T14:14:11","guid":{"rendered":"http:\/\/www.illaa.org\/?p=130"},"modified":"2022-08-22T09:15:48","modified_gmt":"2022-08-22T14:15:48","slug":"entrevista-en-pagina-siete-acerca-de-simidic","status":"publish","type":"post","link":"http:\/\/www.illaa.org\/index.php\/entrevista-en-pagina-siete-acerca-de-simidic\/","title":{"rendered":"Entrevista en P\u00e1gina Siete acerca de SimiDic"},"content":{"rendered":"<div class=\"entry\">\n<p>Tuvimos una entravista con P\u00e1gina Siete acerca de los 23 diccionarios de lenguas originarias que hemos metido en la aplicaci\u00f3n SimiDic para celulares y tabletas de Android y Apple.\u00a0 Jose Laura Yapita coment\u00f3, \u201cEstamos haciendo que la tecnolog\u00eda se adec\u00fae a las lenguas originarias. Queremos que la gente ya no piense que su lengua est\u00e1 desvalorizada o que tenga una actitud negativa ante su propia lengua.\u201d<\/p>\n<p>Lea el articulo \u201c<a title=\"Lanzan diccionarios en takana, movima y t'simane para celulares\" href=\"https:\/\/web.archive.org\/web\/20160317014758\/http:\/\/www.paginasiete.bo\/miradas\/2015\/4\/19\/lanzan-diccionarios-takana-movima-tsimane-para-celular-53834.html\" target=\"_blank\" rel=\"noopener\">Lanzan diccionarios en takana, movima y t\u2019simane para celular<\/a>\u201d en P\u00e1gina Siete.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tuvimos una entravista con P\u00e1gina Siete acerca de los 23 diccionarios de lenguas originarias que hemos metido en la aplicaci\u00f3n SimiDic para celulares y tabletas de Android y Apple.\u00a0 Jose Laura Yapita coment\u00f3, \u201cEstamos haciendo que la tecnolog\u00eda se adec\u00fae &hellip; <a href=\"http:\/\/www.illaa.org\/index.php\/entrevista-en-pagina-siete-acerca-de-simidic\/\">Continuar leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/posts\/130"}],"collection":[{"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":1,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"predecessor-version":[{"id":131,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/posts\/130\/revisions\/131"}],"wp:attachment":[{"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.illaa.org\/index.php\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}